

{"id":31101,"date":"2022-06-30T12:34:57","date_gmt":"2022-06-30T11:34:57","guid":{"rendered":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg"},"modified":"2022-06-30T12:34:57","modified_gmt":"2022-06-30T11:34:57","slug":"img_2370","status":"inherit","type":"attachment","link":"https:\/\/www.patentattorneys.ch\/de\/2022\/06\/30\/8eme-edition-du-bbq-de-linnovation-un-grand-succes-malgre-la-meteo-menacante\/img_2370\/","title":{"rendered":"IMG_2370"},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"de","enabled_languages":["fr","de","en","it"],"languages":{"fr":{"title":true},"de":{"title":false},"en":{"title":false},"it":{"title":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>IMG_2370<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMG_2370\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg\" \/>\n<meta property=\"og:site_name\" content=\"P&amp;TS AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PTS.Ltd\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2592\" \/>\n\t<meta property=\"og:image:height\" content=\"1728\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@PTSSA\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg\",\"url\":\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg\",\"name\":\"IMG_2370\",\"isPartOf\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#website\"},\"datePublished\":\"2022-06-30T11:34:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.patentattorneys.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"8\u00e8me \u00e9dition du BBQ de l&#8217;Innovation : un grand succ\u00e8s malgr\u00e9 la m\u00e9t\u00e9o mena\u00e7ante !\",\"item\":\"https:\/\/www.patentattorneys.ch\/de\/2022\/06\/30\/8eme-edition-du-bbq-de-linnovation-un-grand-succes-malgre-la-meteo-menacante\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IMG_2370\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#website\",\"url\":\"https:\/\/www.patentattorneys.ch\/de\/\",\"name\":\"P&amp;TS AG\",\"description\":\"Patentanw\u00e4lte\",\"publisher\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.patentattorneys.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#organization\",\"name\":\"P&TS SA\",\"url\":\"https:\/\/www.patentattorneys.ch\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2016\/01\/PTS_Icon.jpg\",\"contentUrl\":\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2016\/01\/PTS_Icon.jpg\",\"width\":512,\"height\":512,\"caption\":\"P&TS SA\"},\"image\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/PTS.Ltd\/\",\"https:\/\/x.com\/PTSSA\",\"https:\/\/www.linkedin.com\/company\/p&ts-sa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMG_2370","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg","og_locale":"de_DE","og_type":"article","og_title":"IMG_2370","og_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg","og_site_name":"P&amp;TS AG","article_publisher":"https:\/\/www.facebook.com\/PTS.Ltd\/","og_image":[{"width":2592,"height":1728,"url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@PTSSA","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg","url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg","name":"IMG_2370","isPartOf":{"@id":"https:\/\/www.patentattorneys.ch\/de\/#website"},"datePublished":"2022-06-30T11:34:57+00:00","breadcrumb":{"@id":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.patentattorneys.ch\/"},{"@type":"ListItem","position":2,"name":"8\u00e8me \u00e9dition du BBQ de l&#8217;Innovation : un grand succ\u00e8s malgr\u00e9 la m\u00e9t\u00e9o mena\u00e7ante !","item":"https:\/\/www.patentattorneys.ch\/de\/2022\/06\/30\/8eme-edition-du-bbq-de-linnovation-un-grand-succes-malgre-la-meteo-menacante\/"},{"@type":"ListItem","position":3,"name":"IMG_2370"}]},{"@type":"WebSite","@id":"https:\/\/www.patentattorneys.ch\/de\/#website","url":"https:\/\/www.patentattorneys.ch\/de\/","name":"P&amp;TS AG","description":"Patentanw\u00e4lte","publisher":{"@id":"https:\/\/www.patentattorneys.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patentattorneys.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.patentattorneys.ch\/de\/#organization","name":"P&TS SA","url":"https:\/\/www.patentattorneys.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2016\/01\/PTS_Icon.jpg","contentUrl":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2016\/01\/PTS_Icon.jpg","width":512,"height":512,"caption":"P&TS SA"},"image":{"@id":"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PTS.Ltd\/","https:\/\/x.com\/PTSSA","https:\/\/www.linkedin.com\/company\/p&ts-sa"]}]}},"description":{"rendered":"<p class=\"attachment\"><a rel=\"prettyPhoto[pp_gal]\" href='https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-300x200.jpg 300w, https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-768x512.jpg 768w, https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-1024x683.jpg 1024w, https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-600x400.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1707,"file":"2022\/06\/IMG_2370.jpg","sizes":{"thumbnail":{"file":"IMG_2370-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-150x150.jpg"},"medium":{"file":"IMG_2370-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-300x200.jpg"},"medium_large":{"file":"IMG_2370-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-768x512.jpg"},"large":{"file":"IMG_2370-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-1024x683.jpg"},"blog":{"file":"IMG_2370-1000x563.jpg","width":1000,"height":563,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-1000x563.jpg"},"mini":{"file":"IMG_2370-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-80x80.jpg"},"portfolio":{"file":"IMG_2370-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-600x400.jpg"},"regular":{"file":"IMG_2370-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-500x500.jpg"},"wide":{"file":"IMG_2370-1000x500.jpg","width":1000,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-1000x500.jpg"},"tall":{"file":"IMG_2370-500x1000.jpg","width":500,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-500x1000.jpg"},"widetall":{"file":"IMG_2370-1000x1000.jpg","width":1000,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370-1000x1000.jpg"},"full":{"file":"IMG_2370.jpg","width":2560,"height":1707,"mime_type":"image\/jpeg","source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg"}},"image_meta":{"aperture":"5.6","credit":"","camera":"Canon EOS 700D","caption":"","created_timestamp":"1656443151","copyright":"","focal_length":"76","iso":"400","shutter_speed":"0.008","title":"","orientation":"1","keywords":[]}},"post":31085,"source_url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2022\/06\/IMG_2370.jpg","_links":{"self":[{"href":"https:\/\/www.patentattorneys.ch\/de\/wp-json\/wp\/v2\/media\/31101"}],"collection":[{"href":"https:\/\/www.patentattorneys.ch\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.patentattorneys.ch\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.patentattorneys.ch\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patentattorneys.ch\/de\/wp-json\/wp\/v2\/comments?post=31101"}]}}