

{"id":33511,"date":"2024-02-28T02:58:08","date_gmt":"2024-02-28T01:58:08","guid":{"rendered":"https:\/\/r42o4bftuk.preview.infomaniak.website\/?p=33511"},"modified":"2024-03-20T03:01:11","modified_gmt":"2024-03-20T02:01:11","slug":"1er-mars-jour-ferie-dans-le-canton-de-neuchatel","status":"publish","type":"post","link":"https:\/\/www.patentattorneys.ch\/en\/2024\/02\/28\/pts-is-closed-on-1st-march-neuchatel-public-holiday-2\/","title":{"rendered":"P&#038;TS is closed on 1st March : Neuch\u00e2tel public holiday"},"content":{"rendered":"<p>P&amp;TS Neuch\u00e2tel is closed on Friday 1st March for a public holiday in the canton of Neuch\u00e2tel. P&amp;TS Z\u00fcrich remains available.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>P&amp;TS Neuch\u00e2tel is closed on Friday 1st March for a public holiday in the canton of Neuch\u00e2tel. P&amp;TS Z\u00fcrich remains available.<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"en","enabled_languages":["fr","de","en","it"],"languages":{"fr":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false},"it":{"title":false,"content":false,"excerpt":false}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>P&amp;TS is closed on 1st March : Neuch\u00e2tel public holiday - P&amp;TS Ltd<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P&amp;TS is closed on 1st March : Neuch\u00e2tel public holiday - P&amp;TS Ltd\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/\" \/>\n<meta property=\"og:site_name\" content=\"P&amp;TS Ltd\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PTS.Ltd\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-28T01:58:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T02:01:11+00:00\" \/>\n<meta name=\"author\" content=\"inox\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@PTSSA\" \/>\n<meta name=\"twitter:site\" content=\"@PTSSA\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"inox\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/\"},\"author\":{\"name\":\"inox\",\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/person\/c512a369fdc73b9ca00416113d2ca738\"},\"headline\":\"P&#038;TS is closed on 1st March : Neuch\u00e2tel public holiday\",\"datePublished\":\"2024-02-28T01:58:08+00:00\",\"dateModified\":\"2024-03-20T02:01:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/\"},\"wordCount\":120,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#organization\"},\"articleSection\":[\"Non class\u00e9\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/\",\"url\":\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/\",\"name\":\"P&TS is closed on 1st March : Neuch\u00e2tel public holiday - P&amp;TS Ltd\",\"isPartOf\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#website\"},\"datePublished\":\"2024-02-28T01:58:08+00:00\",\"dateModified\":\"2024-03-20T02:01:11+00:00\",\"description\":\"{:fr}Comme chaque ann\u00e9e, nos bureaux sur Neuch\u00e2tel seront ferm\u00e9 vendredi 1er mars 2024, le jour de l'ind\u00e9pendance neuch\u00e2teloise. P&amp;TS Z\u00fcrich reste\",\"breadcrumb\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.patentattorneys.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P&#038;TS is closed on 1st March : Neuch\u00e2tel public holiday\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#website\",\"url\":\"https:\/\/www.patentattorneys.ch\/de\/\",\"name\":\"P&amp;TS Ltd\",\"description\":\"Intellectual Property\",\"publisher\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.patentattorneys.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#organization\",\"name\":\"P&TS SA\",\"url\":\"https:\/\/www.patentattorneys.ch\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2016\/01\/PTS_Icon.jpg\",\"contentUrl\":\"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2016\/01\/PTS_Icon.jpg\",\"width\":512,\"height\":512,\"caption\":\"P&TS SA\"},\"image\":{\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/PTS.Ltd\/\",\"https:\/\/x.com\/PTSSA\",\"https:\/\/www.linkedin.com\/company\/p&ts-sa\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/person\/c512a369fdc73b9ca00416113d2ca738\",\"name\":\"inox\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/22108fc736fb8590172c17e1f82d4bfd?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/22108fc736fb8590172c17e1f82d4bfd?s=96&r=g\",\"caption\":\"inox\"},\"url\":\"https:\/\/www.patentattorneys.ch\/en\/author\/inox\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P&TS is closed on 1st March : Neuch\u00e2tel public holiday - P&amp;TS Ltd","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/","og_locale":"en_US","og_type":"article","og_title":"P&TS is closed on 1st March : Neuch\u00e2tel public holiday - P&amp;TS Ltd","og_url":"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/","og_site_name":"P&amp;TS Ltd","article_publisher":"https:\/\/www.facebook.com\/PTS.Ltd\/","article_published_time":"2024-02-28T01:58:08+00:00","article_modified_time":"2024-03-20T02:01:11+00:00","author":"inox","twitter_card":"summary_large_image","twitter_creator":"@PTSSA","twitter_site":"@PTSSA","twitter_misc":{"Written by":"inox","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/#article","isPartOf":{"@id":"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/"},"author":{"name":"inox","@id":"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/person\/c512a369fdc73b9ca00416113d2ca738"},"headline":"P&#038;TS is closed on 1st March : Neuch\u00e2tel public holiday","datePublished":"2024-02-28T01:58:08+00:00","dateModified":"2024-03-20T02:01:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/"},"wordCount":120,"commentCount":0,"publisher":{"@id":"https:\/\/www.patentattorneys.ch\/de\/#organization"},"articleSection":["Non class\u00e9"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/","url":"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/","name":"P&TS is closed on 1st March : Neuch\u00e2tel public holiday - P&amp;TS Ltd","isPartOf":{"@id":"https:\/\/www.patentattorneys.ch\/de\/#website"},"datePublished":"2024-02-28T01:58:08+00:00","dateModified":"2024-03-20T02:01:11+00:00","description":"{:fr}Comme chaque ann\u00e9e, nos bureaux sur Neuch\u00e2tel seront ferm\u00e9 vendredi 1er mars 2024, le jour de l'ind\u00e9pendance neuch\u00e2teloise. P&amp;TS Z\u00fcrich reste","breadcrumb":{"@id":"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.patentattorneys.ch\/2024\/02\/28\/1er-mars-jour-ferie-dans-le-canton-de-neuchatel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.patentattorneys.ch\/"},{"@type":"ListItem","position":2,"name":"P&#038;TS is closed on 1st March : Neuch\u00e2tel public holiday"}]},{"@type":"WebSite","@id":"https:\/\/www.patentattorneys.ch\/de\/#website","url":"https:\/\/www.patentattorneys.ch\/de\/","name":"P&amp;TS Ltd","description":"Intellectual Property","publisher":{"@id":"https:\/\/www.patentattorneys.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.patentattorneys.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.patentattorneys.ch\/de\/#organization","name":"P&TS SA","url":"https:\/\/www.patentattorneys.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2016\/01\/PTS_Icon.jpg","contentUrl":"https:\/\/www.patentattorneys.ch\/wp-content\/uploads\/2016\/01\/PTS_Icon.jpg","width":512,"height":512,"caption":"P&TS SA"},"image":{"@id":"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PTS.Ltd\/","https:\/\/x.com\/PTSSA","https:\/\/www.linkedin.com\/company\/p&ts-sa"]},{"@type":"Person","@id":"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/person\/c512a369fdc73b9ca00416113d2ca738","name":"inox","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.patentattorneys.ch\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/22108fc736fb8590172c17e1f82d4bfd?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22108fc736fb8590172c17e1f82d4bfd?s=96&r=g","caption":"inox"},"url":"https:\/\/www.patentattorneys.ch\/en\/author\/inox\/"}]}},"_links":{"self":[{"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/posts\/33511"}],"collection":[{"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/comments?post=33511"}],"version-history":[{"count":3,"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/posts\/33511\/revisions"}],"predecessor-version":[{"id":33515,"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/posts\/33511\/revisions\/33515"}],"wp:attachment":[{"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/media?parent=33511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/categories?post=33511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.patentattorneys.ch\/en\/wp-json\/wp\/v2\/tags?post=33511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}